{"id":112,"count":1,"description":"","link":"https:\/\/adventureaday.blog\/index.php\/tag\/denver-press-club\/","name":"Denver Press Club","slug":"denver-press-club","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/adventureaday.blog\/index.php\/wp-json\/wp\/v2\/tags\/112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adventureaday.blog\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/adventureaday.blog\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/adventureaday.blog\/index.php\/wp-json\/wp\/v2\/posts?tags=112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}