{"id":121,"count":2,"description":"","link":"https:\/\/adventureaday.blog\/index.php\/tag\/frederick-douglass\/","name":"Frederick Douglass","slug":"frederick-douglass","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/adventureaday.blog\/index.php\/wp-json\/wp\/v2\/tags\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adventureaday.blog\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/adventureaday.blog\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/adventureaday.blog\/index.php\/wp-json\/wp\/v2\/posts?tags=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}