{"id":91,"count":1,"description":"","link":"https:\/\/adventureaday.blog\/index.php\/tag\/spaceport\/","name":"Spaceport","slug":"spaceport","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/adventureaday.blog\/index.php\/wp-json\/wp\/v2\/tags\/91","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adventureaday.blog\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/adventureaday.blog\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/adventureaday.blog\/index.php\/wp-json\/wp\/v2\/posts?tags=91"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}